{"id":1313,"date":"2021-02-23T18:50:44","date_gmt":"2021-02-23T18:50:44","guid":{"rendered":"https:\/\/hexagram.uqam.ca\/composite-26\/"},"modified":"2021-07-08T21:38:31","modified_gmt":"2021-07-08T21:38:31","slug":"composite-26","status":"publish","type":"post","link":"https:\/\/hexagram.ca\/fr\/composite-26\/","title":{"rendered":"COMPOSITE #26"},"content":{"rendered":"<p>Molior en collaboration avec Hexagram et le Centre des sciences de Montr\u00e9al est heureux d\u2019accueillir la soir\u00e9e <b>COMPOSITE #26<\/b>.<br \/> <b>Jeudi, 25 f\u00e9vrier \u2013 18 \u00e0 20h<\/b> <\/p>\n<p> Pour participer en tant que spectateur (virtuellement), veuillez RSVP ici: <a href='https:\/\/forms.gle\/TvJrPrp1Yuh3zSCE9' target=\"_blank\" rel=\"noopener\">https:\/\/forms.gle\/TvJrPrp1Yuh3zSCE9<\/a> <\/p>\n<p>  <b>COMPOSITE<\/b> est un rendez-vous bimestriel de r\u00e9seautage d\u00e9di\u00e9 \u00e0 la cr\u00e9ativit\u00e9 num\u00e9rique. Il est n\u00e9 d\u2019une initiative du Conseil des arts de Montr\u00e9al et organis\u00e9 \u00e0 chaque fois par un organisme culturel diff\u00e9rent en collaboration avec une entreprise de l\u2019industrie num\u00e9rique. Cet \u00e9v\u00e9nement a pour objectif de cr\u00e9er un espace de rencontre r\u00e9current entre le milieu de l\u2019art et de l\u2019industrie du secteur num\u00e9rique, en incitant la rencontre et la pollinisation entre cr\u00e9ateurs, centres d\u2019artistes, organismes, entreprises et professionnels du num\u00e9rique.   <!--more-->  <\/p>\n<p>  Chaque COMPOSITE se d\u00e9roule selon une m\u00eame structure. Un blitz Minute Inspiration introduit la soir\u00e9e: 10 acteurs du num\u00e9rique disposent chacun d\u2019une minute pour partager un projet qui a r\u00e9cemment eu un impact sur eux, les a inspir\u00e9s, touch\u00e9s. S\u2019ensuivent 6 pr\u00e9sentations keynote, durant chacune 6 minutes, des projets s\u00e9lectionn\u00e9s au pr\u00e9alable par le comit\u00e9 COMPOSITE suite \u00e0 cet appel \u00e0 projets. Ils peuvent \u00eatre issus du milieu de l\u2019art, de l\u2019industrie ou de l\u2019innovation sociale; le fil directeur est leur capacit\u00e9 commune \u00e0 inspirer, stimuler l\u2019innovation et \u00e9veiller chez les spectateurs une envie de d\u00e9couverte et d\u2019exploration. L\u2019\u00e9v\u00e8nement se conclut par une soir\u00e9e de r\u00e9seautage, de discussions, pour permettre \u00e0 la fois aux pr\u00e9sentateurs et aux participants de tisser des liens et d\u2019\u00e9toffer leurs projets respectifs.<br \/> <b>Pour cette \u00e9dition, COMPOSITE met \u00e0 l\u2019honneur la collaboration.<\/b> L\u2019\u00e9v\u00e8nement sera l\u2019occasion de pr\u00e9senter des projets dans lesquels les strat\u00e9gies collaboratives ou les approches solidaires occupent une place importante et originale. <\/p>\n<p>  Ont \u00e9t\u00e9 retenu pour pr\u00e9sentation, les travaux des membres-\u00e9tudiant.e.s Hexagram <b>Ahreum Lee [Universit\u00e9 Concordia]<\/b> qui pr\u00e9sentera l\u2019installation vid\u00e9o <i>Multiple Selves<\/i>, et <b>K\u00e9 Medley [Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi] <\/b>avec le projet <i>Compartment_Complex<\/i>. <\/p>\n<p>  <a href=\"http:\/\/www.molior.ca\" style=\"color: blue;\">\u00c0 PROPOS DE MOLIOR<\/a> <br \/> Molior est un organisme sp\u00e9cialis\u00e9 dans la production d\u2019expositions et de projets artistiques qui utilisent les technologies comme moyen de cr\u00e9ation, d\u2019expression et d\u2019action. Depuis sa fondation en 2001, Molior a pr\u00e9sent\u00e9 un grand nombre de projets innovateurs aussi bien au Canada que sur la sc\u00e8ne internationale en collaboration avec de multiples partenaires de diffusion. Molior m\u00e8ne \u00e9galement plusieurs activit\u00e9s en dehors des r\u00e9seaux \u00e9tablis afin d\u2019encourager le d\u00e9veloppement des publics et de favoriser l\u2019acc\u00e8s \u00e0 des r\u00e9alisations de premier plan. <\/p>\n<p>  <a href=\"https:\/\/www.montrealsciencecentre.com\" style=\"color: blue;\">\u00c0 PROPOS DU CENTRE DES SCIENCES DE MONTR\u00c9AL<\/a> <br \/> Le Centre des sciences de Montr\u00e9al est un mus\u00e9e d\u00e9di\u00e9 \u00e0 la science et \u00e0 la technologie. Il se d\u00e9marque par son approche interactive et par la mise en valeur de l\u2019innovation et du savoir-faire des gens d\u2019ici. Depuis 2000, il a accueilli plus de 10 millions de visiteurs, dont 2 millions d\u2019\u00e9l\u00e8ves. <\/p>\n<p>  <a href=\"https:\/\/www.artsmontreal.org\/en\" style=\"color: blue;\">\u00c0 PROPOS DU CONSEIL DES ARTS DE MONTR\u00c9AL<\/a> <br \/> Partenaire dynamique de la cr\u00e9ation artistique professionnelle montr\u00e9alaise, le Conseil des arts de Montr\u00e9al rep\u00e8re, accompagne, soutient et reconna\u00eet l&rsquo;excellence dans la cr\u00e9ation, la production et la diffusion artistiques. Il encourage l\u2019ouverture, la d\u00e9couverte et l\u2019audace au c\u0153ur du paysage artistique montr\u00e9alais par ses actions structurantes. Depuis 1956, le Conseil des arts de Montr\u00e9al contribue au d\u00e9veloppement de \u00abMontr\u00e9al, m\u00e9tropole culturelle \u00bb. <\/p>\n<p> Contact: composite.mtl@gmail.com <\/p>\n<p> <img decoding=\"async\" src=\"https:\/\/hexagram.uqam.ca\/wp-content\/uploads\/logo_layout.jpg\" alt=\"\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Molior en collaboration avec Hexagram et le Centre des sciences de Montr\u00e9al est heureux d\u2019accueillir la soir\u00e9e COMPOSITE #26. Jeudi, 25 f\u00e9vrier \u2013 18 \u00e0 20h Pour participer en tant que spectateur (virtuellement), veuillez RSVP ici: https:\/\/forms.gle\/TvJrPrp1Yuh3zSCE9 COMPOSITE est un rendez-vous bimestriel de r\u00e9seautage d\u00e9di\u00e9 \u00e0 la cr\u00e9ativit\u00e9 num\u00e9rique. Il est n\u00e9 d\u2019une initiative du [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":1309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,17],"tags":[],"class_list":["post-1313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites","category-conferences"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COMPOSITE #26 - hexagram.ca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hexagram.ca\/fr\/composite-26\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPOSITE #26 - hexagram.ca\" \/>\n<meta property=\"og:description\" content=\"Molior en collaboration avec Hexagram et le Centre des sciences de Montr\u00e9al est heureux d\u2019accueillir la soir\u00e9e COMPOSITE #26. Jeudi, 25 f\u00e9vrier \u2013 18 \u00e0 20h Pour participer en tant que spectateur (virtuellement), veuillez RSVP ici: https:\/\/forms.gle\/TvJrPrp1Yuh3zSCE9 COMPOSITE est un rendez-vous bimestriel de r\u00e9seautage d\u00e9di\u00e9 \u00e0 la cr\u00e9ativit\u00e9 num\u00e9rique. Il est n\u00e9 d\u2019une initiative du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hexagram.ca\/fr\/composite-26\/\" \/>\n<meta property=\"og:site_name\" content=\"hexagram.ca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HexagramNetwork\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-23T18:50:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-08T21:38:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1211\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Matt Halpenny\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HexagramNetwork\" \/>\n<meta name=\"twitter:site\" content=\"@HexagramNetwork\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matt Halpenny\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/\"},\"author\":{\"name\":\"Matt Halpenny\",\"@id\":\"https:\/\/hexagram.ca\/fr\/#\/schema\/person\/042299703247bf2518922b65513ec641\"},\"headline\":\"COMPOSITE #26\",\"datePublished\":\"2021-02-23T18:50:44+00:00\",\"dateModified\":\"2021-07-08T21:38:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/\"},\"wordCount\":610,\"publisher\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png\",\"articleSection\":[\"activit\u00e9s\",\"conf\u00e9rences\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/\",\"url\":\"https:\/\/hexagram.ca\/fr\/composite-26\/\",\"name\":\"COMPOSITE #26 - hexagram.ca\",\"isPartOf\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png\",\"datePublished\":\"2021-02-23T18:50:44+00:00\",\"dateModified\":\"2021-07-08T21:38:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hexagram.ca\/fr\/composite-26\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage\",\"url\":\"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png\",\"contentUrl\":\"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png\",\"width\":1211,\"height\":681},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hexagram.ca\/fr\/composite-26\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/hexagram.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMPOSITE #26\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hexagram.ca\/fr\/#website\",\"url\":\"https:\/\/hexagram.ca\/fr\/\",\"name\":\"hexagram.ca\",\"description\":\"R\u00e9seau de recherche-cr\u00e9ation en arts, cultures et technologies.\",\"publisher\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hexagram.ca\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hexagram.ca\/fr\/#organization\",\"name\":\"hexagram.ca\",\"url\":\"https:\/\/hexagram.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hexagram.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/hexagram.ca\/wp-content\/uploads\/HEXAGRAM-logo_Colour-02-e1681827308467.png\",\"contentUrl\":\"http:\/\/hexagram.ca\/wp-content\/uploads\/HEXAGRAM-logo_Colour-02-e1681827308467.png\",\"width\":450,\"height\":450,\"caption\":\"hexagram.ca\"},\"image\":{\"@id\":\"https:\/\/hexagram.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/HexagramNetwork\",\"https:\/\/x.com\/HexagramNetwork\",\"https:\/\/www.instagram.com\/hexagram.network\/\",\"https:\/\/www.youtube.com\/channel\/UCrkTxcWUd83yrgt9f67qCUQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/hexagram.ca\/fr\/#\/schema\/person\/042299703247bf2518922b65513ec641\",\"name\":\"Matt Halpenny\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hexagram.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/95a0d5d75f6794cd2d83d060cf23e71a459240f3f4a5441a4880a862d48c549e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/95a0d5d75f6794cd2d83d060cf23e71a459240f3f4a5441a4880a862d48c549e?s=96&d=mm&r=g\",\"caption\":\"Matt Halpenny\"},\"url\":\"https:\/\/hexagram.ca\/fr\/author\/mhalpenny\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMPOSITE #26 - hexagram.ca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hexagram.ca\/fr\/composite-26\/","og_locale":"fr_FR","og_type":"article","og_title":"COMPOSITE #26 - hexagram.ca","og_description":"Molior en collaboration avec Hexagram et le Centre des sciences de Montr\u00e9al est heureux d\u2019accueillir la soir\u00e9e COMPOSITE #26. Jeudi, 25 f\u00e9vrier \u2013 18 \u00e0 20h Pour participer en tant que spectateur (virtuellement), veuillez RSVP ici: https:\/\/forms.gle\/TvJrPrp1Yuh3zSCE9 COMPOSITE est un rendez-vous bimestriel de r\u00e9seautage d\u00e9di\u00e9 \u00e0 la cr\u00e9ativit\u00e9 num\u00e9rique. Il est n\u00e9 d\u2019une initiative du [&hellip;]","og_url":"https:\/\/hexagram.ca\/fr\/composite-26\/","og_site_name":"hexagram.ca","article_publisher":"https:\/\/www.facebook.com\/HexagramNetwork","article_published_time":"2021-02-23T18:50:44+00:00","article_modified_time":"2021-07-08T21:38:31+00:00","og_image":[{"width":1211,"height":681,"url":"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png","type":"image\/png"}],"author":"Matt Halpenny","twitter_card":"summary_large_image","twitter_creator":"@HexagramNetwork","twitter_site":"@HexagramNetwork","twitter_misc":{"\u00c9crit par":"Matt Halpenny","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hexagram.ca\/fr\/composite-26\/#article","isPartOf":{"@id":"https:\/\/hexagram.ca\/fr\/composite-26\/"},"author":{"name":"Matt Halpenny","@id":"https:\/\/hexagram.ca\/fr\/#\/schema\/person\/042299703247bf2518922b65513ec641"},"headline":"COMPOSITE #26","datePublished":"2021-02-23T18:50:44+00:00","dateModified":"2021-07-08T21:38:31+00:00","mainEntityOfPage":{"@id":"https:\/\/hexagram.ca\/fr\/composite-26\/"},"wordCount":610,"publisher":{"@id":"https:\/\/hexagram.ca\/fr\/#organization"},"image":{"@id":"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage"},"thumbnailUrl":"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png","articleSection":["activit\u00e9s","conf\u00e9rences"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/hexagram.ca\/fr\/composite-26\/","url":"https:\/\/hexagram.ca\/fr\/composite-26\/","name":"COMPOSITE #26 - hexagram.ca","isPartOf":{"@id":"https:\/\/hexagram.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage"},"image":{"@id":"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage"},"thumbnailUrl":"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png","datePublished":"2021-02-23T18:50:44+00:00","dateModified":"2021-07-08T21:38:31+00:00","breadcrumb":{"@id":"https:\/\/hexagram.ca\/fr\/composite-26\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hexagram.ca\/fr\/composite-26\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hexagram.ca\/fr\/composite-26\/#primaryimage","url":"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png","contentUrl":"https:\/\/hexagram.ca\/wp-content\/uploads\/Composite26_couv_Facebook_1200x628px-bottom-logo.png","width":1211,"height":681},{"@type":"BreadcrumbList","@id":"https:\/\/hexagram.ca\/fr\/composite-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/hexagram.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"COMPOSITE #26"}]},{"@type":"WebSite","@id":"https:\/\/hexagram.ca\/fr\/#website","url":"https:\/\/hexagram.ca\/fr\/","name":"hexagram.ca","description":"R\u00e9seau de recherche-cr\u00e9ation en arts, cultures et technologies.","publisher":{"@id":"https:\/\/hexagram.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hexagram.ca\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hexagram.ca\/fr\/#organization","name":"hexagram.ca","url":"https:\/\/hexagram.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hexagram.ca\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/hexagram.ca\/wp-content\/uploads\/HEXAGRAM-logo_Colour-02-e1681827308467.png","contentUrl":"http:\/\/hexagram.ca\/wp-content\/uploads\/HEXAGRAM-logo_Colour-02-e1681827308467.png","width":450,"height":450,"caption":"hexagram.ca"},"image":{"@id":"https:\/\/hexagram.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HexagramNetwork","https:\/\/x.com\/HexagramNetwork","https:\/\/www.instagram.com\/hexagram.network\/","https:\/\/www.youtube.com\/channel\/UCrkTxcWUd83yrgt9f67qCUQ"]},{"@type":"Person","@id":"https:\/\/hexagram.ca\/fr\/#\/schema\/person\/042299703247bf2518922b65513ec641","name":"Matt Halpenny","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hexagram.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/95a0d5d75f6794cd2d83d060cf23e71a459240f3f4a5441a4880a862d48c549e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/95a0d5d75f6794cd2d83d060cf23e71a459240f3f4a5441a4880a862d48c549e?s=96&d=mm&r=g","caption":"Matt Halpenny"},"url":"https:\/\/hexagram.ca\/fr\/author\/mhalpenny\/"}]}},"_links":{"self":[{"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/posts\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/comments?post=1313"}],"version-history":[{"count":1,"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/posts\/1313\/revisions"}],"predecessor-version":[{"id":1767,"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/posts\/1313\/revisions\/1767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/media\/1309"}],"wp:attachment":[{"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/media?parent=1313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/categories?post=1313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hexagram.ca\/fr\/wp-json\/wp\/v2\/tags?post=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}